{"id":16525,"date":"2020-02-13T23:21:51","date_gmt":"2020-02-13T23:21:51","guid":{"rendered":"https:\/\/nextgensd.com\/?page_id=16525"},"modified":"2020-02-13T23:52:18","modified_gmt":"2020-02-13T23:52:18","slug":"ebird","status":"publish","type":"page","link":"https:\/\/nextgensd.com\/es\/ebird\/","title":{"rendered":"eBird"},"content":{"rendered":"\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfEres usuaria\/o de eBird?<\/h2>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\">\u00a1Tambi\u00e9n puedes participar! Simplemente crea tu lista dentro de tu cuenta eBird y comp\u00e1rtela con la cuenta \u00abBorder BioBlitz\u00bb cuando la sometas. \u00a1Eso es todo!<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Tambi\u00e9n puedes ver las observaciones compartidas durante el BioBlitz a trav\u00e9s de nuestro <a rel=\"noreferrer noopener\" aria-label=\"perfil de eBird (opens in a new tab)\" href=\"https:\/\/ebird.org\/profile\/MTI0MjY1MQ\" target=\"_blank\">perfil en eBird<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfEres usuaria\/o de eBird? \u00a1Tambi\u00e9n puedes participar! Simplemente crea tu lista dentro de tu cuenta eBird y comp\u00e1rtela con la cuenta \u00abBorder BioBlitz\u00bb cuando la sometas. \u00a1Eso es todo! Tambi\u00e9n puedes ver las observaciones compartidas durante el BioBlitz a trav\u00e9s de nuestro perfil en eBird.<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-16525","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/nextgensd.com\/es\/wp-json\/wp\/v2\/pages\/16525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextgensd.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nextgensd.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nextgensd.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/nextgensd.com\/es\/wp-json\/wp\/v2\/comments?post=16525"}],"version-history":[{"count":2,"href":"https:\/\/nextgensd.com\/es\/wp-json\/wp\/v2\/pages\/16525\/revisions"}],"predecessor-version":[{"id":16527,"href":"https:\/\/nextgensd.com\/es\/wp-json\/wp\/v2\/pages\/16525\/revisions\/16527"}],"wp:attachment":[{"href":"https:\/\/nextgensd.com\/es\/wp-json\/wp\/v2\/media?parent=16525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}